{"id":43642,"date":"2026-02-19T15:23:10","date_gmt":"2026-02-19T20:23:10","guid":{"rendered":"https:\/\/homecaresolutionsmtl.com\/services\/la-gestion-des-maladies-chroniques\/"},"modified":"2026-05-12T15:48:16","modified_gmt":"2026-05-12T20:48:16","slug":"la-gestion-des-maladies-chroniques","status":"publish","type":"services","link":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/","title":{"rendered":"La gestion des maladies chroniques"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"43642\" class=\"elementor elementor-43642 elementor-43359\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa4a09 e-flex e-con-boxed cmsmasters-block-default e-con e-parent\" data-id=\"2fa4a09\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d144b3 cmsmasters-block-default cmsmasters-sticky-default elementor-widget elementor-widget-text-editor\" data-id=\"1d144b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tUn \u00e9l\u00e9ment important de la gestion des maladies chroniques est de savoir quand on a besoin d\u2019aide, et o\u00f9 en trouver. Reconna\u00eetre cette n\u00e9cessit\u00e9 ne signifie pas que l\u2019on est victime de sa maladie. Nos pr\u00e9pos\u00e9s attentifs et compatissants offrent un large \u00e9ventail de services, tous adapt\u00e9s \u00e0 vos besoins pr\u00e9cis.<br><br>Par exemple, supposons que vous avez du mal \u00e0 pr\u00e9parer vos repas parce que rester longtemps debout est trop fatigant ou douloureux. Si vous aimez faire la cuisine, vous trouverez difficile de ne plus cuisiner. Nos pr\u00e9pos\u00e9s peuvent venir vous aider \u00e0 effectuer ces t\u00e2ches, afin que vous puissiez continuer de faire ce qui vous tient le plus \u00e0 c\u0153ur.<br><br>L\u2019une de nos infirmi\u00e8res exp\u00e9riment\u00e9es en soins \u00e0 domicile peut aller chez vous faire une \u00e9valuation gratuite afin de cr\u00e9er un plan de soins sur mesure qui tiendra compte de vos besoins particuliers, qu\u2019il s\u2019agisse:<br><ul class=\"wp-block-list\">\r\n \t<li>de soins d\u2019hygi\u00e8ne<\/li>\r\n \t<li>du suivi du r\u00e9gime et de l\u2019alimentation<\/li>\r\n \t<li>du suivi de la prise de m\u00e9dicaments<\/li>\r\n \t<li>de la s\u00e9curit\u00e9<\/li>\r\n \t<li>d\u2019une aide pour les courses<\/li>\r\n \t<li>d\u2019une assistance dans l\u2019entretien de la maison<\/li>\r\n \t<li>de r\u00e9pit pour les aidants naturels<\/li>\r\n \t<li>du suivi de programmes d\u2019exercice personnalis\u00e9s pr\u00e9par\u00e9s par des phytoth\u00e9rapeutes<\/li>\r\n<\/ul><br>Notre but est de vous permettre de rester chez vous et d\u2019y conserver votre autonomie en vous aidant \u00e0 accomplir vos t\u00e2ches quotidiennes en toute s\u00e9curit\u00e9. Au fur et \u00e0 mesure que vos besoins en soins \u00e9voluent, nous sommes pr\u00eats \u00e0 collaborer \u00e9troitement avec vous et votre famille afin d\u2019assurer que vous recevez les services de qualit\u00e9 ax\u00e9s sur la personne qui correspondent \u00e0 votre condition.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8433f6e e-flex e-con-boxed cmsmasters-block-default e-con e-parent\" data-id=\"8433f6e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b00ce1 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start cmsmasters-block-default cmsmasters-sticky-default elementor-widget elementor-widget-icon-box\" data-id=\"5b00ce1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-quote-left\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 256h-80v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8c-88.4 0-160 71.6-160 160v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48zm-288 0H96v-64c0-35.3 28.7-64 64-64h8c13.3 0 24-10.7 24-24V56c0-13.3-10.7-24-24-24h-8C71.6 32 0 103.6 0 192v240c0 26.5 21.5 48 48 48h128c26.5 0 48-21.5 48-48V304c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSolutions soins \u00e0 domicile a procur\u00e9 \u00e0 notre p\u00e8re des soins incomparables au cours des cinq derni\u00e8res ann\u00e9es. Gr\u00e2ce \u00e0 un personnel attentionn\u00e9 et comp\u00e9tent, notre p\u00e8re a pu poursuivre ses travaux acad\u00e9miques et continuer de voyage malgr\u00e9 un \u00e9tat physique \u00e9prouvant. D\u2019une ann\u00e9e \u00e0 l\u2019autre, Solutions soins \u00e0 domicile nous a aid\u00e9s \u00e0 \u00e9valuer ses besoins et a r\u00e9guli\u00e8rement offert des solutions pour am\u00e9liorer sa qualit\u00e9 de vie, optimiser sa sant\u00e9 et g\u00e9rer sa vie quotidienne.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Un \u00e9l\u00e9ment important de la gestion des maladies chroniques est de savoir quand on a besoin d\u2019aide, et o\u00f9 en trouver. Reconna\u00eetre cette n\u00e9cessit\u00e9 ne signifie pas que l\u2019on est victime de sa maladie. Nos pr\u00e9pos\u00e9s attentifs et compatissants offrent un large \u00e9ventail de services, tous adapt\u00e9s \u00e0 vos besoins pr\u00e9cis.<\/p>\n","protected":false},"featured_media":43636,"template":"","meta":{"_acf_changed":false},"service_category":[68],"class_list":["post-43642","services","type-services","status-publish","has-post-thumbnail","hentry","service_category-soins-specialises"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La gestion des maladies chroniques - Solutions soins \u00e0 domicile Montr\u00e9al<\/title>\n<meta name=\"description\" content=\"Un \u00e9l\u00e9ment important de la gestion des maladies chroniques est de savoir quand on a besoin d\u2019aide, et o\u00f9 en trouver. Reconna\u00eetre cette n\u00e9cessit\u00e9 ne signifie pas que l\u2019on est victime de sa maladie. Nos pr\u00e9pos\u00e9s attentifs et compatissants offrent un large \u00e9ventail de services, tous adapt\u00e9s \u00e0 vos besoins pr\u00e9cis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La gestion des maladies chroniques - Solutions soins \u00e0 domicile Montr\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Un \u00e9l\u00e9ment important de la gestion des maladies chroniques est de savoir quand on a besoin d\u2019aide, et o\u00f9 en trouver. Reconna\u00eetre cette n\u00e9cessit\u00e9 ne signifie pas que l\u2019on est victime de sa maladie. Nos pr\u00e9pos\u00e9s attentifs et compatissants offrent un large \u00e9ventail de services, tous adapt\u00e9s \u00e0 vos besoins pr\u00e9cis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/\" \/>\n<meta property=\"og:site_name\" content=\"Solutions soins \u00e0 domicile Montr\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Solutionsmontreal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T20:48:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/homecaresolutionsmtl.com\/wp-content\/uploads\/2026\/02\/managing-chronic-illness-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1005\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/services\\\/la-gestion-des-maladies-chroniques\\\/\",\"url\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/services\\\/la-gestion-des-maladies-chroniques\\\/\",\"name\":\"La gestion des maladies chroniques - Solutions soins \u00e0 domicile Montr\u00e9al\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/services\\\/la-gestion-des-maladies-chroniques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/services\\\/la-gestion-des-maladies-chroniques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/managing-chronic-illness-scaled.jpg\",\"datePublished\":\"2026-02-19T20:23:10+00:00\",\"dateModified\":\"2026-05-12T20:48:16+00:00\",\"description\":\"Un \u00e9l\u00e9ment important de la gestion des maladies chroniques est de savoir quand on a besoin d\u2019aide, et o\u00f9 en trouver. Reconna\u00eetre cette n\u00e9cessit\u00e9 ne signifie pas que l\u2019on est victime de sa maladie. Nos pr\u00e9pos\u00e9s attentifs et compatissants offrent un large \u00e9ventail de services, tous adapt\u00e9s \u00e0 vos besoins pr\u00e9cis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/services\\\/la-gestion-des-maladies-chroniques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/services\\\/la-gestion-des-maladies-chroniques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/services\\\/la-gestion-des-maladies-chroniques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/managing-chronic-illness-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/managing-chronic-illness-scaled.jpg\",\"width\":2560,\"height\":1005,\"caption\":\"Infirmier \u00e0 domicile prenant soin d\u2019une femme \u00e2g\u00e9e.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/services\\\/la-gestion-des-maladies-chroniques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acceuil\",\"item\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La gestion des maladies chroniques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/\",\"name\":\"Homecare Solutions Montreal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/#organization\",\"name\":\"Soins \u00e0 Domicile Solutions\",\"url\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Soins \u00e0 Domicile Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/homecaresolutionsmtl.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Solutionsmontreal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La gestion des maladies chroniques - Solutions soins \u00e0 domicile Montr\u00e9al","description":"Un \u00e9l\u00e9ment important de la gestion des maladies chroniques est de savoir quand on a besoin d\u2019aide, et o\u00f9 en trouver. Reconna\u00eetre cette n\u00e9cessit\u00e9 ne signifie pas que l\u2019on est victime de sa maladie. Nos pr\u00e9pos\u00e9s attentifs et compatissants offrent un large \u00e9ventail de services, tous adapt\u00e9s \u00e0 vos besoins pr\u00e9cis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/","og_locale":"fr_FR","og_type":"article","og_title":"La gestion des maladies chroniques - Solutions soins \u00e0 domicile Montr\u00e9al","og_description":"Un \u00e9l\u00e9ment important de la gestion des maladies chroniques est de savoir quand on a besoin d\u2019aide, et o\u00f9 en trouver. Reconna\u00eetre cette n\u00e9cessit\u00e9 ne signifie pas que l\u2019on est victime de sa maladie. Nos pr\u00e9pos\u00e9s attentifs et compatissants offrent un large \u00e9ventail de services, tous adapt\u00e9s \u00e0 vos besoins pr\u00e9cis.","og_url":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/","og_site_name":"Solutions soins \u00e0 domicile Montr\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Solutionsmontreal","article_modified_time":"2026-05-12T20:48:16+00:00","og_image":[{"width":2560,"height":1005,"url":"https:\/\/homecaresolutionsmtl.com\/wp-content\/uploads\/2026\/02\/managing-chronic-illness-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/","url":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/","name":"La gestion des maladies chroniques - Solutions soins \u00e0 domicile Montr\u00e9al","isPartOf":{"@id":"https:\/\/homecaresolutionsmtl.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/#primaryimage"},"image":{"@id":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/#primaryimage"},"thumbnailUrl":"https:\/\/homecaresolutionsmtl.com\/wp-content\/uploads\/2026\/02\/managing-chronic-illness-scaled.jpg","datePublished":"2026-02-19T20:23:10+00:00","dateModified":"2026-05-12T20:48:16+00:00","description":"Un \u00e9l\u00e9ment important de la gestion des maladies chroniques est de savoir quand on a besoin d\u2019aide, et o\u00f9 en trouver. Reconna\u00eetre cette n\u00e9cessit\u00e9 ne signifie pas que l\u2019on est victime de sa maladie. Nos pr\u00e9pos\u00e9s attentifs et compatissants offrent un large \u00e9ventail de services, tous adapt\u00e9s \u00e0 vos besoins pr\u00e9cis.","breadcrumb":{"@id":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/#primaryimage","url":"https:\/\/homecaresolutionsmtl.com\/wp-content\/uploads\/2026\/02\/managing-chronic-illness-scaled.jpg","contentUrl":"https:\/\/homecaresolutionsmtl.com\/wp-content\/uploads\/2026\/02\/managing-chronic-illness-scaled.jpg","width":2560,"height":1005,"caption":"Infirmier \u00e0 domicile prenant soin d\u2019une femme \u00e2g\u00e9e."},{"@type":"BreadcrumbList","@id":"https:\/\/homecaresolutionsmtl.com\/fr\/services\/la-gestion-des-maladies-chroniques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acceuil","item":"https:\/\/homecaresolutionsmtl.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La gestion des maladies chroniques"}]},{"@type":"WebSite","@id":"https:\/\/homecaresolutionsmtl.com\/fr\/#website","url":"https:\/\/homecaresolutionsmtl.com\/fr\/","name":"Homecare Solutions Montreal","description":"","publisher":{"@id":"https:\/\/homecaresolutionsmtl.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homecaresolutionsmtl.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/homecaresolutionsmtl.com\/fr\/#organization","name":"Soins \u00e0 Domicile Solutions","url":"https:\/\/homecaresolutionsmtl.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/homecaresolutionsmtl.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Soins \u00e0 Domicile Solutions"},"image":{"@id":"https:\/\/homecaresolutionsmtl.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Solutionsmontreal"]}]}},"_links":{"self":[{"href":"https:\/\/homecaresolutionsmtl.com\/fr\/wp-json\/wp\/v2\/services\/43642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homecaresolutionsmtl.com\/fr\/wp-json\/wp\/v2\/services"}],"about":[{"href":"https:\/\/homecaresolutionsmtl.com\/fr\/wp-json\/wp\/v2\/types\/services"}],"version-history":[{"count":9,"href":"https:\/\/homecaresolutionsmtl.com\/fr\/wp-json\/wp\/v2\/services\/43642\/revisions"}],"predecessor-version":[{"id":44767,"href":"https:\/\/homecaresolutionsmtl.com\/fr\/wp-json\/wp\/v2\/services\/43642\/revisions\/44767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/homecaresolutionsmtl.com\/fr\/wp-json\/wp\/v2\/media\/43636"}],"wp:attachment":[{"href":"https:\/\/homecaresolutionsmtl.com\/fr\/wp-json\/wp\/v2\/media?parent=43642"}],"wp:term":[{"taxonomy":"service_category","embeddable":true,"href":"https:\/\/homecaresolutionsmtl.com\/fr\/wp-json\/wp\/v2\/service_category?post=43642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}